{"id":272,"date":"2019-09-17T11:25:21","date_gmt":"2019-09-17T09:25:21","guid":{"rendered":"http:\/\/demo.duadv.net\/poggiolagrognola\/news-e-eventi-2\/"},"modified":"2019-09-25T15:47:33","modified_gmt":"2019-09-25T13:47:33","slug":"news-e-eventi","status":"publish","type":"page","link":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/","title":{"rendered":"News &#038; Events"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-272","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>News e eventi turismo in Umbria | Poggio La Grognola | Cannara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News e eventi turismo in Umbria | Poggio La Grognola | Cannara\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/\" \/>\n<meta property=\"og:site_name\" content=\"Poggio La Grognola\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-25T13:47:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/\",\"url\":\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/\",\"name\":\"News e eventi turismo in Umbria | Poggio La Grognola | Cannara\",\"isPartOf\":{\"@id\":\"https:\/\/www.poggiolagrognola.it\/#website\"},\"datePublished\":\"2019-09-17T09:25:21+00:00\",\"dateModified\":\"2019-09-25T13:47:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.poggiolagrognola.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News &#038; Events\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.poggiolagrognola.it\/#website\",\"url\":\"https:\/\/www.poggiolagrognola.it\/\",\"name\":\"Poggio La Grognola\",\"description\":\"Bed &amp; Breakfast Cannara\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.poggiolagrognola.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News e eventi turismo in Umbria | Poggio La Grognola | Cannara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/","og_locale":"en_US","og_type":"article","og_title":"News e eventi turismo in Umbria | Poggio La Grognola | Cannara","og_url":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/","og_site_name":"Poggio La Grognola","article_modified_time":"2019-09-25T13:47:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/","url":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/","name":"News e eventi turismo in Umbria | Poggio La Grognola | Cannara","isPartOf":{"@id":"https:\/\/www.poggiolagrognola.it\/#website"},"datePublished":"2019-09-17T09:25:21+00:00","dateModified":"2019-09-25T13:47:33+00:00","breadcrumb":{"@id":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.poggiolagrognola.it\/en\/news-e-eventi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.poggiolagrognola.it\/en\/"},{"@type":"ListItem","position":2,"name":"News &#038; Events"}]},{"@type":"WebSite","@id":"https:\/\/www.poggiolagrognola.it\/#website","url":"https:\/\/www.poggiolagrognola.it\/","name":"Poggio La Grognola","description":"Bed &amp; Breakfast Cannara","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.poggiolagrognola.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/pages\/272"}],"collection":[{"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":1,"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/pages\/272\/revisions"}],"predecessor-version":[{"id":277,"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/pages\/272\/revisions\/277"}],"wp:attachment":[{"href":"https:\/\/www.poggiolagrognola.it\/en\/wp-json\/wp\/v2\/media?parent=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}